{"id":1355,"date":"2022-03-14T11:43:45","date_gmt":"2022-03-14T10:43:45","guid":{"rendered":"https:\/\/weprotect-health.com\/?p=1355"},"modified":"2022-03-14T11:43:47","modified_gmt":"2022-03-14T10:43:47","slug":"%f0%9f%91%8avous-etes-taxi-ou-ambulance-conventionne-par-les-organismes-dassurances-maladies-vous-souhaitez-rendre-les-trajets-de-votre-patientele-encore-plus-agreable-%f0%9f%98%80%f0%9f%92%a5","status":"publish","type":"post","link":"https:\/\/weprotect-health.com\/en\/2022\/03\/14\/%f0%9f%91%8avous-etes-taxi-ou-ambulance-conventionne-par-les-organismes-dassurances-maladies-vous-souhaitez-rendre-les-trajets-de-votre-patientele-encore-plus-agreable-%f0%9f%98%80%f0%9f%92%a5\/","title":{"rendered":"\ud83d\udc4aVous \u00eates #Taxi ou #ambulance, conventionn\u00e9 par les organismes d&rsquo;assurances maladies ? Vous souhaitez rendre les trajets de votre patient\u00e8le encore plus agr\u00e9able ?\ud83d\ude00\ud83d\udca5Diff\u00e9renciez vous et affichez le !\ud83d\udca5"},"content":{"rendered":"<p><br>\ud83d\udc49Savez vous combien il est p\u00e9nible pour un malade rentrant par exemple de #chimioth\u00e9rapie, d&rsquo;effectuer un trajet en v\u00e9hicule?<\/p>\n\n\n\n<p><br>\ud83d\udc49Et dans votre v\u00e9hicule malheureusement, m\u00eame avec un tr\u00e8s bon niveau de confort, le malade ne se sent pas bien, mais comme il est bien \u00e9lev\u00e9 ou par pudeur, il n&rsquo;en parle pas. Ce niveau de confort est parfois contreproductif car souvent associ\u00e9 a de nouvelles technologies, qui elles, sont impactantes sur la biologie humaine&#8230;\ud83e\udd14<\/p>\n\n\n\n<p><br>\ud83d\udc49L&rsquo;air de l&rsquo;habitacle si il est renouvel\u00e9, est tr\u00e8s souvent mal filtr\u00e9, pour la simple et bonne raison , que nous ne changeons pas le filtre assez r\u00e9guli\u00e8rement. Et m\u00eame bien filtr\u00e9, l&rsquo;air reste mal d\u00e9pollu\u00e9 et mal d\u00e9contamin\u00e9.<\/p>\n\n\n\n<p> \ud83d\ude0cQuant \u00e0 l&rsquo;\u00e9lectromagn\u00e9tisme d\u00e9gag\u00e9 par l&rsquo;ensemble des technologies embarqu\u00e9es, il accompagne souvent l&rsquo;absence de r\u00e9silience de l&rsquo;organisme, le stress, les douleurs, les maux de t\u00eates, la fatigue, le manque de concentration et de r\u00e9flexion.\ud83d\ude0c Peut \u00eatre m\u00eame que vous \u00eates vous m\u00eame surmen\u00e9 en fin de journ\u00e9e&#8230;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Appelez nous!       02 55 89 02 04<\/p>\n\n\n\n<p><br>\ud83d\udc49Nous vous accompagnerons \ud83d\ude4cpour \u00e9quiper vos v\u00e9hicules, pour votre bien \u00eatre et Sant\u00e9 mais \u00e9galement et surtout pour le bien-\u00eatre et la sant\u00e9 de votre patient\u00e8le !<\/p>\n\n\n\n<p><br>#sant\u00e9 #innovation <\/p>\n\n\n\n<p>Loco Num\u00e9rique P\u00e9pini\u00e8re d&rsquo;entreprises La Roche sur Yon Agglom\u00e9ration Centre de Ressources en Innovation de La Roche-sur-Yon Agglom\u00e9ration Vend\u00e9e &#8211; L&rsquo;essentiel vient du c\u0153ur BNI V&amp;B &#8211; Vend\u00e9e &amp; Business<\/p>","protected":false},"excerpt":{"rendered":"<p>\ud83d\udc49Savez vous combien il est p\u00e9nible pour un malade rentrant par exemple de #chimioth\u00e9rapie, d&rsquo;effectuer un trajet en v\u00e9hicule? \ud83d\udc49Et&#8230;<\/p>","protected":false},"author":1,"featured_media":1356,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/posts\/1355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/comments?post=1355"}],"version-history":[{"count":1,"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/posts\/1355\/revisions"}],"predecessor-version":[{"id":1357,"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/posts\/1355\/revisions\/1357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/media\/1356"}],"wp:attachment":[{"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/media?parent=1355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/categories?post=1355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/tags?post=1355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}