{"id":1107,"date":"2021-08-05T10:50:33","date_gmt":"2021-08-05T08:50:33","guid":{"rendered":"https:\/\/weprotect-health.com\/?p=1107"},"modified":"2021-08-05T10:50:36","modified_gmt":"2021-08-05T08:50:36","slug":"%f0%9f%94%a5entretien-spontane-ce-matin-avec-une-commercante-electro-hyper-sensible%f0%9f%94%a5-ehs","status":"publish","type":"post","link":"https:\/\/weprotect-health.com\/en\/2021\/08\/05\/%f0%9f%94%a5entretien-spontane-ce-matin-avec-une-commercante-electro-hyper-sensible%f0%9f%94%a5-ehs\/","title":{"rendered":"\ud83d\udd25Entretien spontan\u00e9 ce matin avec une commer\u00e7ante Electro Hyper sensible\ud83d\udd25 (EHS)"},"content":{"rendered":"<p><strong>Elle n&rsquo;est pas encore reconnue par la m\u00e9decine&#8230;\ud83d\ude14&#8230; alors que je n&rsquo;ai pas mis longtemps a reconna\u00eetre la symptomatologie&#8230;<\/strong><\/p>\n\n\n\n<p><strong><br>\ud83d\udc49Et pourtant tout ce qu&rsquo;elle m&rsquo;\u00e9nonce fait partie des sympt\u00f4mes classiques apr\u00e8s en moyenne une dizaine d&rsquo;ann\u00e9e de surexposition aux rayonnements \u00e9lectromagn\u00e9tiques, aux \u00e9crans, aux technologie sans fils.\ud83e\uddd0 C&rsquo;est m\u00eame ce qui l&rsquo;a \u00e9loign\u00e9 de son vrai m\u00e9tier&#8230; Ing\u00e9nieur syst\u00e8me&#8230;son m\u00e9decin se refuse \u00e0 l&rsquo;envoyer consulter dans l&rsquo;une des 24 consultations ouvertes en France sur le sujet\u2639\ufe0f lui pr\u00e9f\u00e9rant un cocktail d&rsquo;antid\u00e9presseur et d&rsquo;anxiolytiques qui la fatiguent encore plus.<\/strong><\/p>\n\n\n\n<p><strong><br>\ud83d\udc49Je lui ai donc rappel\u00e9 qu&rsquo;elle n&rsquo;avait pas besoin de lui pour prendre RDV, m\u00eame sans lettre d&rsquo;introduction&#8230; pour rappel cette pathologie d\u00e9sormais reconnue, touche 2\/3 de femmes&#8230;et cela s&rsquo;explique tr\u00e8s facilement par leur constitution organique et biologique.\ud83e\uddd0<\/strong><\/p>\n\n\n\n<p><strong><br>\ud83d\udc49Maux de t\u00eate incessants, bourdonnements d&rsquo;oreilles, palpitations\ud83d\udc94et sentiment d&rsquo;oppression, fatigu\u00e9e outre mesure, troubles du sommeil, r\u00e9flexion parfois incoh\u00e9rente \ud83e\udde0, mauvaises prises de d\u00e9cision dans sa gestion quotidienne, et bien d&rsquo;autres probl\u00e8mes dont l&rsquo;\u00e9nonc\u00e9 vous paraitrait un peu long&#8230;<\/strong><\/p>\n\n\n\n<p><strong><br>\ud83d\udc49Si vous rencontrez des sympt\u00f4mes diffus, mal expliqu\u00e9s, de la fatigue a n&rsquo;en plus pouvoir, et vous sentir ext\u00e9nu\u00e9(e) en fin de journ\u00e9e&#8230; Venez \u00e9changer sur le fil de la discussion, ces probl\u00e8mes r\u00e9sultent de pollutions invisibles difficilement accessibles&#8230;<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Elle n&rsquo;est pas encore reconnue par la m\u00e9decine&#8230;\ud83d\ude14&#8230; alors que je n&rsquo;ai pas mis longtemps a reconna\u00eetre la symptomatologie&#8230; \ud83d\udc49Et&#8230;<\/p>","protected":false},"author":1,"featured_media":1108,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/posts\/1107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/comments?post=1107"}],"version-history":[{"count":1,"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/posts\/1107\/revisions"}],"predecessor-version":[{"id":1109,"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/posts\/1107\/revisions\/1109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/media\/1108"}],"wp:attachment":[{"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/media?parent=1107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/categories?post=1107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/weprotect-health.com\/en\/wp-json\/wp\/v2\/tags?post=1107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}